{"id":9159,"date":"2025-12-18T03:39:34","date_gmt":"2025-12-18T02:39:34","guid":{"rendered":"https:\/\/www.nti-audio.com\/accessories\/adaptateur-dentree-sortie-numerique-pcb"},"modified":"2026-05-13T11:47:15","modified_gmt":"2026-05-13T09:47:15","slug":"adaptateur-dentree-sortie-numerique-pcb","status":"publish","type":"accessories","link":"https:\/\/www.nti-audio.com\/fr\/accessoires\/adaptateur-dentree-sortie-numerique-pcb","title":{"rendered":"Adaptateur d&#8217;Entr\u00e9e\/Sortie num\u00e9rique PCB"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>L\u2019analyseur XL3 ou XL2, associ\u00e9 \u00e0 l\u2019adaptateur E\/S num\u00e9rique, contr\u00f4le des p\u00e9riph\u00e9riques externes, par exemple une grande lampe de signalisation rouge-orange-verte indiquant les d\u00e9passements de niveaux sonores. L\u2019adaptateur E\/S num\u00e9rique se connecte \u00e0 l\u2019interface E\/S num\u00e9rique de l\u2019analyseur XL2. <\/p>\n","protected":false},"featured_media":9161,"menu_order":34,"template":"","application-group":[],"product-cats":[57,16],"software-group":[],"class_list":{"0":"post-9159","1":"accessories","2":"type-accessories","3":"status-publish","4":"has-post-thumbnail","6":"product-cats-xl2-audio-acoustic-analyzer","7":"product-cats-xl3-acoustic-analyzer"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/accessories\/9159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/accessories"}],"about":[{"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/types\/accessories"}],"version-history":[{"count":1,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/accessories\/9159\/revisions"}],"predecessor-version":[{"id":13231,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/accessories\/9159\/revisions\/13231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/media\/9161"}],"wp:attachment":[{"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/media?parent=9159"}],"wp:term":[{"taxonomy":"application-group","embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/application-group?post=9159"},{"taxonomy":"product-cats","embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/product-cats?post=9159"},{"taxonomy":"software-group","embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/software-group?post=9159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}