{"id":8637,"date":"2024-07-08T04:03:00","date_gmt":"2024-07-08T02:03:00","guid":{"rendered":"https:\/\/www.nti-audio.com\/mesure-de-lintelligibilite-de-la-parole-stipa-sur-lanalyseur-acoustique-xl3"},"modified":"2026-02-20T15:57:34","modified_gmt":"2026-02-20T14:57:34","slug":"mesure-de-lintelligibilite-de-la-parole-stipa-sur-lanalyseur-acoustique-xl3","status":"publish","type":"post","link":"https:\/\/www.nti-audio.com\/fr\/societe\/actualites\/mesure-de-lintelligibilite-de-la-parole-stipa-sur-lanalyseur-acoustique-xl3","title":{"rendered":"Mesure de l&#8217;intelligibilit\u00e9 de la parole STIPA sur l&#8217;Analyseur Acoustique XL3"},"content":{"rendered":"\n<figure class=\"wp-block-image alignwide size-full\"><img decoding=\"async\" width=\"670\" height=\"325\" src=\"https:\/\/www.nti-audio.com\/wp-content\/uploads\/nti-audio-teaser-xl3-stipa-670x325-1.webp\" alt=\"Nti Audio Teaser Xl3 Stipa 670x325\" class=\"wp-image-5502\" srcset=\"https:\/\/www.nti-audio.com\/wp-content\/uploads\/nti-audio-teaser-xl3-stipa-670x325-1.webp 670w, https:\/\/www.nti-audio.com\/wp-content\/uploads\/nti-audio-teaser-xl3-stipa-670x325-1-500x243.webp 500w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L&#8217;Analyseur Acoustique XL3 prend d\u00e9sormais en charge les mesures d&#8217;intelligibilit\u00e9 de la parole conform\u00e9ment \u00e0 la norme IEC60268-16. Associ\u00e9 aux sources de signaux TalkBox (acoustique) et MR-PRO (\u00e9lectrique), l&#8217;XL3 est l&#8217;outil id\u00e9al pour des t\u00e2ches de mesure STIPA efficaces et fiables. Les valeurs mesur\u00e9es peuvent \u00eatre facilement visualis\u00e9es dans un rapport.  <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les mesures STIPA (Speech Transmission Index for Public Address Systems) sont effectu\u00e9es pour \u00e9valuer l&#8217;intelligibilit\u00e9 de la parole des syst\u00e8mes de sonorisation dans diff\u00e9rents environnements. En g\u00e9n\u00e9ral, les mesures STIPA sont r\u00e9alis\u00e9es dans les salles de conf\u00e9rence et les salles de classe, sur les syst\u00e8mes d&#8217;annonce des transports publics, dans les th\u00e9\u00e2tres, les stades, les h\u00f4pitaux et bien d&#8217;autres lieux. Si un syst\u00e8me de sonorisation est con\u00e7u pour des annonces d&#8217;urgence li\u00e9es \u00e0 la s\u00e9curit\u00e9, l&#8217;exigence minimale pour les valeurs STIPA doit \u00eatre d\u00e9montr\u00e9e par la mesure et la documentation.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La mesure<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le signal de test STIPA est introduit, soit acoustiquement, soit \u00e9lectriquement, dans le syst\u00e8me de sonorisation. Les valeurs STIPA sont ensuite enregistr\u00e9es avec l&#8217;XL3 en diff\u00e9rents points de la zone publique concern\u00e9e. Les valeurs mesur\u00e9es sont affich\u00e9es num\u00e9riquement et class\u00e9es.  <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"250\" height=\"437\" data-id=\"5504\" src=\"https:\/\/www.nti-audio.com\/wp-content\/uploads\/XL3-STIPA-numerics.webp\" alt=\"Xl3 Stipa Numerics\" class=\"wp-image-5504\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"250\" height=\"437\" data-id=\"5503\" src=\"https:\/\/www.nti-audio.com\/wp-content\/uploads\/XL3-STIPA-ambient-noise.webp\" alt=\"Xl3 Stipa Bruit Ambiant\" class=\"wp-image-5503\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"250\" height=\"437\" data-id=\"5505\" src=\"https:\/\/www.nti-audio.com\/wp-content\/uploads\/XL3-STIPA-numerics-with-noise.webp\" alt=\"Xl3 Stipa Numerics With Noise\" class=\"wp-image-5505\"\/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Influence du bruit de fond<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un facteur important pour l&#8217;intelligibilit\u00e9 de la parole est la pr\u00e9sence de bruit de fond. Comme il n&#8217;est souvent pas pratique de diffuser le signal de test STIPA pendant les heures d&#8217;exploitation typiques (par exemple, un th\u00e9\u00e2tre rempli de monde), l&#8217;Analyseur Acoustique XL3 permet d&#8217;enregistrer les niveaux de bruit de fond lorsque le lieu est plein, et d&#8217;enregistrer les mesures STIPA s\u00e9par\u00e9ment, lorsque le lieu est vide. Ces mesures peuvent ensuite \u00eatre combin\u00e9es ult\u00e9rieurement.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Moyennage<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le calcul de la moyenne de plusieurs mesures en un point est pris en charge par un \u00e9cran d\u00e9di\u00e9. Ici, l&#8217;utilisateur conserve les informations collect\u00e9es sur les mesures individuelles et les \u00e9carts entre elles. Les mesures non valides peuvent \u00eatre \u00e9cart\u00e9es imm\u00e9diatement.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Rapport de mesure<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Avec l&#8217;outil de rapport STIPA, qui est disponible gratuitement, les mesures effectu\u00e9es \u00e0 plusieurs positions peuvent \u00eatre facilement r\u00e9sum\u00e9es dans un rapport de mesure.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1127\" height=\"543\" src=\"https:\/\/www.nti-audio.com\/wp-content\/uploads\/XL3-STIPA-SummaryReport-with-Screen.webp\" alt=\"\" class=\"wp-image-5506\" srcset=\"https:\/\/www.nti-audio.com\/wp-content\/uploads\/XL3-STIPA-SummaryReport-with-Screen.webp 1127w, https:\/\/www.nti-audio.com\/wp-content\/uploads\/XL3-STIPA-SummaryReport-with-Screen-750x361.webp 750w, https:\/\/www.nti-audio.com\/wp-content\/uploads\/XL3-STIPA-SummaryReport-with-Screen-500x241.webp 500w\" sizes=\"(max-width: 1127px) 100vw, 1127px\" \/><figcaption class=\"wp-element-caption\"><em>Rapport de synth\u00e8se STI<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez plus d&#8217;informations et de nombreux conseils utiles sur la mani\u00e8re d&#8217;effectuer des mesures STIPA sur notre <a href=\"https:\/\/www.nti-audio.com\/fr\/applications\/systemes-devacuation-vocale\/intelligibilite-de-la-parole-stipa\" data-type=\"link\" data-id=\"https:\/\/www.nti-audio.com\/fr\/applications\/systemes-devacuation-vocale\/intelligibilite-de-la-parole-stipa\">site web d&#8217;application STIPA<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La fonction STIPA est disponible sur l&#8217;XL3 \u00e0 partir du firmware V1.36. Vous avez \u00e9galement besoin de : <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.nti-audio.com\/fr\/options\/option-stipa\" data-type=\"options\" data-id=\"8934\">600 000 712 Option XL3 STIPA <\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme alternative \u00e0 cette licence permanente, il existe \u00e9galement une version de 365 jours<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>600 000 725 Option XL3 STIPA 365 <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(trouvez ceci et d&#8217;autres options pour le Sonom\u00e8tre XL3 <a href=\"https:\/\/www.nti-audio.com\/fr\/options\" data-type=\"link\" data-id=\"https:\/\/www.nti-audio.com\/fr\/produits\/sonometres\/analyseur-acoustique-xl3#options\" target=\"_blank\" rel=\"noopener\">ici<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le firmware V1.36 est disponible en t\u00e9l\u00e9chargement gratuit pour tous les appareils XL3.<br>Une <a href=\"https:\/\/www.youtube.com\/watch?v=OMSLcZiOZG4\" target=\"_blank\" rel=\"noopener\">courte vid\u00e9o<\/a> montre comment cela fonctionne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avez-vous des questions ou souhaitez-vous une offre sans engagement ?<br>Contactez-nous \u00e0 l&#8217;adresse <a href=\"mailto:info@nti-audio.com\">info@nti-audio.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Analyseur Acoustique XL3 prend d\u00e9sormais en charge les mesures d&#8217;intelligibilit\u00e9 de la parole conform\u00e9ment \u00e0 la norme IEC60268-16. Associ\u00e9 aux sources de signaux TalkBox (acoustique) et MR-PRO (\u00e9lectrique), l&#8217;XL3 est l&#8217;outil id\u00e9al pour des t\u00e2ches de mesure STIPA efficaces et fiables. Les valeurs mesur\u00e9es peuvent \u00eatre facilement visualis\u00e9es dans un rapport. Les mesures STIPA (Speech [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[540],"tags":[],"application-group":[],"product-cats":[],"software-group":[],"class_list":["post-8637","post","type-post","status-publish","format-standard","category-actualites"],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/posts\/8637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/comments?post=8637"}],"version-history":[{"count":0,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/posts\/8637\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/media?parent=8637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/categories?post=8637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/tags?post=8637"},{"taxonomy":"application-group","embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/application-group?post=8637"},{"taxonomy":"product-cats","embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/product-cats?post=8637"},{"taxonomy":"software-group","embeddable":true,"href":"https:\/\/www.nti-audio.com\/fr\/wp-json\/wp\/v2\/software-group?post=8637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}